{"id":11583,"date":"2024-01-28T22:09:54","date_gmt":"2024-01-28T21:09:54","guid":{"rendered":"https:\/\/dev.jstindt.com\/preiserstattungsdossiers-deutschland\/"},"modified":"2024-06-10T17:08:09","modified_gmt":"2024-06-10T16:08:09","slug":"preis-erstattung-nutzenbewertung-dossiers-deutschland","status":"publish","type":"page","link":"https:\/\/jstindt.com\/de\/preis-erstattung-nutzenbewertung-dossiers-deutschland\/","title":{"rendered":"Preis- Und Erstattungsdossiers \/ Nutzenbewertungsdossiers in Deutschland"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11583\" class=\"elementor elementor-11583 elementor-3962\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f02a91f e-flex e-con-boxed e-con e-parent\" data-id=\"4f02a91f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2f5d4135 e-con-full e-flex e-con e-child\" data-id=\"2f5d4135\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bff5a0d elementor-widget elementor-widget-text-editor\" data-id=\"5bff5a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In der vielf\u00e4ltigen Landschaft der Preis- und Erstattungsdossiers in Deutschland stellt Justin Stindt Consultants eine kompetente Beratungsagentur dar, die sich darauf spezialisiert hat, Unternehmen durch das komplexe deutsche Erstattungs\u00f6kosystem zu f\u00fchren. Als globale Beratungsagentur verf\u00fcgt unser Unternehmen \u00fcber ein internationales Expertenteam, das sich mit Marktzugangsstrategien in der Bundesrepublik Deutschland bestens auskennt. Unsere Berater und Spezialisten setzen sich daf\u00fcr ein, dass pharmazeutische Innovationen den strengen Vorschriften des deutschen Marktes entsprechen. Als vertrauensw\u00fcrdiger Auftragnehmer ist die Expertise unserer Agentur von entscheidender Bedeutung f\u00fcr diejenigen, die ein Dossier zur deutschen Nutzenbewertung (AMNOG) verstehen und liefern m\u00f6chten, das mit den Anforderungen des G-BA und IQWiG in Einklang steht. Arbeiten Sie mit Justin Stindt Consultants zusammen, um unsere umfassenden Erkenntnisse zu nutzen und nachhaltige Preis- und Erstattungsergebnisse in Deutschland zu erzielen.     <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73beafcf title_Txt_Img-block e-flex e-con-boxed e-con e-parent\" data-id=\"73beafcf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f672627 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5f672627\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verst\u00e4ndnis der Auswirkungen der AMNOG-Reform auf Dossiers zur Preisgestaltung und Erstattung im Gesundheitswesen in Deutschland<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b747e0d e-con-full e-flex e-con e-child\" data-id=\"7b747e0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58c0065d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"58c0065d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Dossier zur Deutschen Nutzenbewertung (AMNOG).<\/h3>\n<p>Die AMNOG-Reform von 2011 hat zu einer strengeren Pr\u00fcfung neuer Arzneimittelzulassungen gef\u00fchrt und sich somit auf das Preispotenzial ausgewirkt. Das Nutzenbewertungsdossier (\u201eAMNOG-Dossier\u201c) ist ein wesentlicher Bestandteil der Zusatznutzenbewertung und es ist von grundlegender Bedeutung, ein vollst\u00e4ndiges, zutreffendes und an den Anforderungen des Gemeinsamen Bundesausschusses (G-BA) und dem Institut f\u00fcr Qualit\u00e4t und Wirtschaftlichkeit im Gesundheitswesen (IQWiG) orientiertes Dossier einzureichen. <\/p>\n<p>Justin Stindt Consultants ist eine auf deutsche Nutzenbewertungsdossiers spezialisierte Agentur. Unser erfahrenes Team aus Beratern und Experten hilft Ihnen dabei, den patientenrelvanten Zusatznutzen Ihres Produkts im AMNOG-Dossier zu artikulieren <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec9bdea image-inblock elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1ec9bdea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"482\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-germany.webp\" class=\"attachment-full size-full wp-image-9557\" alt=\"Preis- Und Erstattungsdossiers \/ Nutzenbewertungsdossiers Deutschland\" srcset=\"https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-germany.webp 724w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-germany-300x200.webp 300w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-germany-150x100.webp 150w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<section class=\"elementor-element elementor-element-144f2be3 e-flex e-con-boxed e-con e-parent\" data-id=\"144f2be3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15e9850b elementor-widget elementor-widget-text-editor\" data-id=\"15e9850b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-align: var(--text-align); color: var( --e-global-color-text ); font-size: 16px; text-transform: none;\">Der G-BA legt seiner Zusatznutzenbewertung das vom Hersteller vorgelegte Dossier zugrunde. Viele aktuelle Beschl\u00fcsse fallen in die Kategorien \u201ekein, geringer oder nicht quantifizierbarer Zusatznutzen\u201c, was zu anspruchsvollen Preisverhandlungen mit dem GKV-Spitzenverband f\u00fchren kann. <\/span><\/p>\n<div><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/09\/Pricing-Reimbursement-dossiers-Germany.png\" alt=\"\" width=\"393\" height=\"376\"><\/div>\n<p>Aufgrund der entscheidenden Bedeutung des Dossiers und seiner Inhalte f\u00fcr diese Entscheidung ist es wichtig, ein vollst\u00e4ndiges, korrektes und an den Anforderungen des G-BA und des IQWiG orientiertes Dossier einzureichen. Der optimale Weg, um sicherzustellen, dass die Angaben im Dossier den Anforderungen des G-BA entsprechen, ist ein fr\u00fchzeitiges Beratungsgespr\u00e4ch direkt mit dem G-BA. Weitere Informationen finden Sie in unter <a href=\"https:\/\/jstindt.com\/de\/beratung-nutzenbewertung-deutschland\/\">Beratungsgespr\u00e4che zur Nutzenbewertung \u2013 Deutschland<\/a>  <\/p>\n<p>Obwohl Deutschland nach wie vor ein attraktiver Markt f\u00fcr Pharma, Biotech und MedTech ist, in dem Premiumpreise m\u00f6glich sind, fordert der GKV-Spitzenverband bei Nichterf\u00fcllung der G-BA-Anforderungen erhebliche Preisnachl\u00e4sse, die im schlimmsten Fall dazu f\u00fchren k\u00f6nnen, dass sich Hersteller aus dem deutschen Markt zur\u00fcckziehen.<\/p>\n<p>Arzneimittel mit EMA-Orphan-Designation k\u00f6nnen ein vereinfachtes Dossier zur G-BA-Nutzenbewertung einreichen und m\u00fcssen ihren Zusatznutzen nicht gegen\u00fcber einer zweckm\u00e4\u00dfigen Vergleichstherapie darlegen, sondern lediglich das Ausma\u00df des Zusatznutzens belegen.<\/p>\n<p>Justin Stindt Consultants ist Ihre Agentur f\u00fcr ein optimales AMNOG-Dossier. Unser Team aus erfahrenen Beratern und Experten unterst\u00fctzt Sie bei der Erstellung eines Nutzenbewertungsdossiers, das den Anforderungen des G-BA und des IQWiG entspricht und den Zusatznutzen Ihres Produkts gegen\u00fcber der zweckm\u00e4\u00dfigen Vergleichstherapie herausstellt. <\/p>\n<p>Unsere Agentur wurde von vielen Pharma-, Biotech- und Medtech-Unternehmen als bevorzugter Dienstleister f\u00fcr die Erstellung des deutschen P&amp;R-Dossiers \/ AMNOG-Dossiers ausgew\u00e4hlt. Unser Unternehmen verf\u00fcgt \u00fcber deutsche Muttersprachler mit umfangreicher Erfahrung sowohl in der Industrie als auch in Beratungsagenturen und einer erfolgreichen Erfolgsbilanz bei P&amp;R-Dossiers, die zu einer nachhaltigen Preisgestaltung und Erstattung in Deutschland f\u00fchrt. <\/p>\n<h2>Erstattungswege f\u00fcr Medizinprodukte in Deutschland<\/h2>\n<p>F\u00fcr die Erstattung von Medizinprodukten gibt es in Deutschland unterschiedliche Wege und Justin Stindt Consultants ist die richtige Agentur, um Sie \u00fcber den optimalen Weg f\u00fcr Ihr Medizinprodukt zu beraten. Stoffliche Medizinprodukte k\u00f6nnen ausnahmsweise in die Arzneimittelversorgung nach <a href=\"https:\/\/www.gesetze-im-internet.de\/sgb_5\/__31.html\" target=\"_blank\" rel=\"noopener\">\u00a7 31 SGB V<\/a> einbezogen werden (Positivliste: Anlage V der Verordnung).  <br \/>F\u00fcr Medizinprodukte muss ein Dossier eingereicht werden, damit das Medizinprodukt in Anhang V aufgenommen wird.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1d353fcd e-flex e-con-boxed e-con e-parent\" data-id=\"1d353fcd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7e862e15 e-con-full e-flex e-con e-child\" data-id=\"7e862e15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52ed22b3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"52ed22b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Justin Stindt Consultants: Ihr Partner f\u00fcr den deutschen Marktzugang \u2013 Expertenberatung zu Preis- und Erstattungsdossiers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70aa2bac elementor-widget elementor-widget-text-editor\" data-id=\"70aa2bac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"image-intext alignright wp-image-10254\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-consulting-agency-germany.webp\" alt=\"Beratungsagentur f\u00fcr Preis- und Erstattungsdossiers Deutschland\" width=\"571\" height=\"400\" srcset=\"https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-consulting-agency-germany.webp 705w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-consulting-agency-germany-300x210.webp 300w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/pricing-and-reimbursement-dossiers-consulting-agency-germany-150x105.webp 150w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/><\/p>\n<p><span style=\"text-align: var(--text-align); color: var( --e-global-color-text ); font-size: 16px; text-transform: none;\">Justin Stindt Consultants ist Ihre Agentur, die Sie bei der Erstellung und Einreichung des Nutzenbewertungsdossiers f\u00fcr Arzneimittel und Medizinprodukte ber\u00e4t und unterst\u00fctzt.<\/span><\/p>\n<div>\n<p><span style=\"text-align: var(--text-align); color: var( --e-global-color-text );\">Unser Ziel besteht darin, HTA-Einreichungen zu liefern, die sich durch hervorragende schriftliche Qualit\u00e4t, technische Pr\u00e4zision und die Kunst, klare, \u00fcberzeugende Darstellungen zu verweben, auszeichnen. Unser Ziel ist es, sicherzustellen, dass jede Einreichung einen zusammenh\u00e4ngenden, integrierten, evidenzbasierten Leitfaden darstellt und sich von einer blo\u00dfen Ansammlung unterschiedlicher klinischer und gesundheits\u00f6konomischer Elemente entfernt, die normalerweise in einem Evidenzpaket zu finden sind <\/span><\/p>\n<p>Justin Stindt Consultants ist Ihre globale Agentur mit den richtigen Experten f\u00fcr das Schreiben von AMNOG-Dossiers. Unsere Dienstleistungen umfassen (nicht beschr\u00e4nkt auf): <\/p>\n<ul>\n<li>Umfassende Projektplanung mit klaren Zeitpl\u00e4nen und Meilensteinen<\/li>\n<li>Strategische \u00dcberpr\u00fcfung der Arzneimittelpositionierung<\/li>\n<li>Dossiererstellung, sowohl deutsche Originale als auch englische \u00dcbersetzungen (typischerweise Modul 1)<\/li>\n<li>Dossiervalidierung mit Key Opinion Leaders und ehemaligen Mitgliedern des G-BA oder IQWiG<\/li>\n<li>Anleitung und Unterst\u00fctzung beim Einreichungsprozess<\/li>\n<li>Unterst\u00fctzung beim schriftlichen Stellungnahmeverfahren<\/li>\n<li>Anh\u00f6rungsvorbereitung und -betreuung<\/li>\n<li>Strategische Beratung und Teilnahme an Preisverhandlungen und ggf. Schiedsverfahren<\/li>\n<li>Effektives Projektmanagement und Kommunikation w\u00e4hrend des gesamten Prozesses<\/li>\n<\/ul>\n<div> <\/div>\n<p>Unser Expertenteam verf\u00fcgt \u00fcber umfangreiche Erfahrung darin, unseren Kunden ma\u00dfgeschneiderte Unterst\u00fctzung zu bieten, um deutschen Patienten schnellstm\u00f6glichen Zugang zu nachhaltigen Preis- und Erstattungskonditionen zu erm\u00f6glichen. Wenn Sie nach einem Anbieter suchen, der Sie bei Ihrem deutschen Preis- und Erstattungsdossier unterst\u00fctzt, w\u00e4hlen Sie einen Dienstleister, der alles daran setzt, die HTA-Anerkennung und eine nachhaltige Preisgestaltung f\u00fcr Ihr Produkt zu erm\u00f6glichen. Justin Stindt Consultants ist mehr als ein blo\u00dfer Lieferant und bietet umfassende Serviceunterst\u00fctzung, einschlie\u00dflich der Zusammenarbeit mit den Beh\u00f6rden und Preisverhandlungen.  <\/p>\n<p>Machen Sie Justin Stindt Consultants zu Ihrem vertrauensvollen Agenturpartner bei der Erschlie\u00dfung von Preis- und Erstattungsm\u00f6glichkeiten (P&amp;R) f\u00fcr Ihr Produkt in Deutschland.<\/p>\n<p>Kontaktieren Sie noch heute unsere Spezialisten, um zu erfahren, wie wir unsere Dienstleistungen an Ihre individuellen Bed\u00fcrfnisse anpassen und Ihre Preis- und Erstattungsziele verwirklichen k\u00f6nnen.<span style=\"text-align: var(--text-align); color: var( --e-global-color-text );\"> <\/span><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c5eb94 e-flex e-con-boxed e-con e-parent\" data-id=\"8c5eb94\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-429eea6 elementor-widget elementor-widget-template\" data-id=\"429eea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"11731\" class=\"elementor elementor-11731 elementor-4243 elementor-4243\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8032f3 e-flex e-con-boxed e-con e-parent\" data-id=\"e8032f3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-82ae310 e-flex e-con-boxed e-con e-child\" data-id=\"82ae310\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebf50e elementor-widget elementor-widget-heading\" data-id=\"1ebf50e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Treffen Sie einen unserer Experten f\u00fcr Preis- und Erstattungsdossiers in Deutschland<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f36db6 e-con-full e-flex e-con e-child\" data-id=\"2f36db6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10e7ad1 elementor-widget elementor-widget-image\" data-id=\"10e7ad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/Justin-Stindt.png\" class=\"attachment-large size-large wp-image-10766\" alt=\"Justin Stindt\" srcset=\"https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/Justin-Stindt.png 320w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/Justin-Stindt-300x300.png 300w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/Justin-Stindt-150x150.png 150w, https:\/\/jstindt.com\/wp-content\/uploads\/2024\/01\/Justin-Stindt-96x96.png 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45f9cbe elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"45f9cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tJustin versteht die Dynamik der deutschen P&amp;R-Landschaft und der deutschen AMNOG-Dossiers, einschlie\u00dflich der Bedeutung des Ausma\u00dfes des Zusatznutzens f\u00fcr optimale P&amp;R-Bedingungen. In fr\u00fcheren Projekten hat er intensiv mit lokalen Beh\u00f6rden (G-BA, GKV-SV) zusammengearbeitet, um die positive Positionierung von Pharma-, Biotech- und Medtech-Kunden in Deutschland sicherzustellen. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92d4a2c e-con-full e-flex e-con e-child\" data-id=\"92d4a2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e8f6eec e-con-full e-flex e-con e-child\" data-id=\"e8f6eec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f92faf elementor-widget elementor-widget-heading\" data-id=\"3f92faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nehmen Sie Kontakt mit unserem Experten auf<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-898b135 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"898b135\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;N\\u00e4chste&quot;,&quot;step_previous_label&quot;:&quot;Vorherige&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"contact_form\" name=\"Kontakt zu einem Experten\" aria-label=\"Kontakt zu einem Experten\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"11731\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"898b135\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Strategische Beratung zu Preis- und Erstattungswegen in Frankreich\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"11515\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-firstname elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-firstname\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVorname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[firstname]\" id=\"form-field-firstname\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-lastname elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-lastname\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tFamilienname, Nachname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[lastname]\" id=\"form-field-lastname\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-telephone elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telephone\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[telephone]\" id=\"form-field-telephone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Nur Nummern oder Telefon-Zeichen (#, -, *, etc) werden akzeptiert.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tIhre Anfrage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nachricht senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bab84bc e-con-full e-flex e-con e-parent\" data-id=\"2bab84bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb1c37a elementor-widget elementor-widget-global elementor-global-1366 elementor-widget-template\" data-id=\"cb1c37a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"11717\" class=\"elementor elementor-11717 elementor-1361 elementor-1361\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0aa82b e-con-full e-flex e-con e-parent\" data-id=\"2e0aa82b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cb46b53 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7cb46b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie unser Team<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589789cc elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"589789cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Erfahrenen Marktzugangsspezialisten Sind Nur Einen Klick Entfernt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c90348 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3c90348\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:450}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-grow\" href=\"https:\/\/jstindt.com\/de\/kontaktiere-uns\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktiere Uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b239d7 e-flex e-con-boxed e-con e-parent\" data-id=\"5b239d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a63d3 elementor-widget elementor-widget-heading\" data-id=\"c1a63d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">KUNDENBEWERTUNGEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf1d8e elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"eaf1d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:8444,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t<style id=\"loop-8444\">.elementor-8444 .elementor-element.elementor-element-c2e4169{--display:flex;--justify-content:flex-start;--align-items:center;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--gap:1px 1px;--row-gap:1px;--column-gap:1px;}.elementor-8444 .elementor-element.elementor-element-dde4f1f{text-align:center;font-size:1.3em;font-style:italic;line-height:1.4em;width:var( --container-widget-width, 95% );max-width:95%;--container-widget-width:95%;--container-widget-flex-grow:0;}.elementor-8444 .elementor-element.elementor-element-dde4f1f > .elementor-widget-container{padding:16px 16px 16px 16px;background-color:var( --e-global-color-7bbd0f3 );border-style:solid;border-width:1px 1px 1px 1px;border-color:var( --e-global-color-secondary );}.elementor-8444 .elementor-element.elementor-element-dde4f1f.elementor-element{--align-self:center;}.elementor-8444 .elementor-element.elementor-element-f35d92e{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;}.elementor-8444 .elementor-element.elementor-element-50478c2 img{width:55px;height:55px;object-fit:cover;object-position:center center;border-style:solid;border-width:2px 2px 2px 2px;border-color:var( --e-global-color-primary );border-radius:999px 999px 999px 999px;}.elementor-8444 .elementor-element.elementor-element-50478c2 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-8444 .elementor-element.elementor-element-06be1d8{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--gap:0px 0px;--row-gap:0px;--column-gap:0px;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:20px;--padding-right:20px;}.elementor-8444 .elementor-element.elementor-element-06be1d8.e-con{--align-self:center;--flex-grow:0;--flex-shrink:1;}.elementor-8444 .elementor-element.elementor-element-26324e1{text-align:start;color:var( --e-global-color-secondary );}.elementor-8444 .elementor-element.elementor-element-26324e1 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-8444 .elementor-element.elementor-element-43839e6{text-align:start;font-size:13px;}.elementor-8444 .elementor-element.elementor-element-43839e6 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-8444 .elementor-element.elementor-element-43839e6.elementor-element{--order:99999 \/* order end hack *\/;}@media(min-width:768px){.elementor-8444 .elementor-element.elementor-element-06be1d8{--width:90%;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"8444\" class=\"elementor elementor-8444 swiper-slide e-loop-item e-loop-item-11646 post-11646 testimonial type-testimonial status-publish hentry tag-peter-foertig-de\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-c2e4169 e-con-full e-flex e-con e-parent\" data-id=\"c2e4169\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dde4f1f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dde4f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEs ist eine Freude, mit Justin Stindt Consulting zusammenzuarbeiten. Ihre Professionalit\u00e4t und einfache Kommunikation haben unsere Projekte erheblich verbessert. Das Team von Justin Stindt Consulting verf\u00fcgt \u00fcber fundierte Kenntnisse der HTA-Prozesse in der EU, was es zu einem unsch\u00e4tzbaren Vorteil bei der Navigation durch die komplexen nationalen Erstattungslandschaften macht. Ihr Engagement f\u00fcr Spitzenleistungen und Zusammenarbeit ist wirklich lobenswert.   \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f35d92e e-con-full e-flex e-con e-child\" data-id=\"f35d92e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50478c2 elementor-widget elementor-widget-image\" data-id=\"50478c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Peter-Foertig-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-8228\" alt=\"\" srcset=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Peter-Foertig-150x150.jpg 150w, https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Peter-Foertig-96x96.jpg 96w, https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Peter-Foertig.jpg 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06be1d8 e-con-full e-flex e-con e-child\" data-id=\"06be1d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26324e1 elementor-widget elementor-widget-text-editor\" data-id=\"26324e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPeter Foertig\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43839e6 elementor-widget elementor-widget-text-editor\" data-id=\"43839e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVP Medical Affairs Europe Taiho Oncology Europe GmbH\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"8444\" class=\"elementor elementor-8444 swiper-slide e-loop-item e-loop-item-11647 post-11647 testimonial type-testimonial status-publish hentry tag-eldon-mayer-de\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-c2e4169 e-con-full e-flex e-con e-parent\" data-id=\"c2e4169\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dde4f1f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dde4f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tJustin und sein Team haben ma\u00dfgeblich dazu beigetragen, dass unser Medikament in einer Reihe von EU-L\u00e4ndern f\u00fcr Patienten zug\u00e4nglich und erstattungsf\u00e4hig ist. Durch Justins Fachwissen und sein umfangreiches Netzwerk in der EU war er auch in der Lage, die entsprechenden F\u00e4higkeiten und Kenntnisse bei der Auswahl von EU-L\u00e4ndern anzuwenden, in denen eine Kostenerstattung m\u00f6glich ist. Letztendlich hat Justins Arbeit dazu beigetragen, dass Patienten mit einer schweren, seltenen Krankheit Zugang zu einer lebensverl\u00e4ngernden Behandlung erhalten und gleichzeitig ein wettbewerbsf\u00e4higer Preis und eine Kostenerstattung f\u00fcr das Unternehmen erzielt werden konnten.   \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f35d92e e-con-full e-flex e-con e-child\" data-id=\"f35d92e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50478c2 elementor-widget elementor-widget-image\" data-id=\"50478c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Eldon-Mayer-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-8198\" alt=\"\" srcset=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Eldon-Mayer-150x150.jpg 150w, https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Eldon-Mayer-96x96.jpg 96w, https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Eldon-Mayer.jpg 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06be1d8 e-con-full e-flex e-con e-child\" data-id=\"06be1d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26324e1 elementor-widget elementor-widget-text-editor\" data-id=\"26324e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEldon Mayer\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43839e6 elementor-widget elementor-widget-text-editor\" data-id=\"43839e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChief Commercial Officer Eiger Biopharmaceuticals\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"8444\" class=\"elementor elementor-8444 swiper-slide e-loop-item e-loop-item-11648 post-11648 testimonial type-testimonial status-publish hentry tag-silvia-chiroli-de\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-c2e4169 e-con-full e-flex e-con e-parent\" data-id=\"c2e4169\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dde4f1f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dde4f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIch hatte mehrfach die Gelegenheit, mit Justin und seinem Beratungsteam zu arbeiten, und die Zusammenarbeit war immer \u00e4u\u00dferst positiv. Justin Consulting ist ein Boutique-Beratungsunternehmen, das technisches K\u00f6nnen, Erfahrung und die F\u00e4higkeit, seinen Service auf die Bed\u00fcrfnisse des Kunden zuzuschneiden, miteinander verbindet. Die kurzen Kommunikationswege machen es auch leicht, mit ihnen \u00fcber strategische Themen zu diskutieren, wobei die wichtigsten Berater pers\u00f6nlich involviert sind. Schlie\u00dflich sind alle Mitarbeiter, mit denen ich zusammengearbeitet habe, und insbesondere Justin, immer verf\u00fcgbar, angenehm und offen, so dass die Arbeit mit ihnen ein echtes Vergn\u00fcgen ist.   \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f35d92e e-con-full e-flex e-con e-child\" data-id=\"f35d92e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50478c2 elementor-widget elementor-widget-image\" data-id=\"50478c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Silvia-Chiroli-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-8252\" alt=\"\" srcset=\"https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Silvia-Chiroli-150x150.jpg 150w, https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Silvia-Chiroli-96x96.jpg 96w, https:\/\/jstindt.com\/wp-content\/uploads\/2023\/12\/Silvia-Chiroli.jpg 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06be1d8 e-con-full e-flex e-con e-child\" data-id=\"06be1d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26324e1 elementor-widget elementor-widget-text-editor\" data-id=\"26324e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSilvia Chiroli\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43839e6 elementor-widget elementor-widget-text-editor\" data-id=\"43839e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tHead of Market Access EMEA &amp; CM Italy at argenx\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e24c859 elementor-align-center elementor-widget elementor-widget-global elementor-global-12122 elementor-global-8750 elementor-widget-button\" data-id=\"e24c859\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/jstindt.com\/de\/referenzen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alle Erfahrungsberichte lesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>In der vielf\u00e4ltigen Landschaft der Preis- und Erstattungsdossiers in Deutschland stellt Justin Stindt Consultants eine kompetente Beratungsagentur dar, die sich darauf spezialisiert hat, Unternehmen durch das komplexe deutsche Erstattungs\u00f6kosystem zu f\u00fchren. Als globale Beratungsagentur verf\u00fcgt unser Unternehmen \u00fcber ein internationales Expertenteam, das sich mit Marktzugangsstrategien in der Bundesrepublik Deutschland bestens auskennt. Unsere Berater und Spezialisten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9481,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11583","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/pages\/11583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/comments?post=11583"}],"version-history":[{"count":16,"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/pages\/11583\/revisions"}],"predecessor-version":[{"id":17600,"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/pages\/11583\/revisions\/17600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/media\/9481"}],"wp:attachment":[{"href":"https:\/\/jstindt.com\/de\/wp-json\/wp\/v2\/media?parent=11583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}